{"id":1413,"date":"2019-12-13T20:15:36","date_gmt":"2019-12-13T20:15:36","guid":{"rendered":"https:\/\/falk-toys.com\/crecer-con-falk-toys\/"},"modified":"2025-10-21T09:54:42","modified_gmt":"2025-10-21T07:54:42","slug":"crecer-con-falk-toys","status":"publish","type":"page","link":"https:\/\/falk-toys.com\/es\/crecer-con-falk-toys\/","title":{"rendered":"Crecer con Falk Toys"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1413\" class=\"elementor elementor-1413 elementor-147\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8af4339 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8af4339\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3cd1e709\" data-id=\"3cd1e709\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-365b8645 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"365b8645\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7eeb9582\" data-id=\"7eeb9582\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16994d84 elementor-hidden-phone elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"16994d84\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">CRECER CON FALK TOYS<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24db1561 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-phone elementor-widget elementor-widget-heading\" data-id=\"24db1561\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">DEBUT SECTION MOBILE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e0ea1fa elementor-hidden-desktop elementor-hidden-tablet elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"6e0ea1fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">CRECER CON FALK TOYS<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30f93160 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-toggle\" data-id=\"30f93160\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8211\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-8211\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Los retos de las habilidades motoras<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8211\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-8211\"><p><span class=\"s1\"><b>Durante sus primeros 3 a\u00f1os, el ni\u00f1o desarrollar\u00e1 sus habilidades psicomotoras.<br \/>\n<\/b><\/span><span style=\"font-size: 20px;\">Caminar, correr, empujar, pedalear son actividades que le permitir\u00e1n a su hijo desarrollar sus habilidades motoras globales, un prerrequisito fundamental para el desarrollo de la psicomotricidad fina y m\u00e1s tarde para aprender en la escuela. \u00a1Falk acompa\u00f1a a su hijo en el desarrollo de sus nuevas habilidades mientras se divierte!<\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8212\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-8212\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Hacer como \"los adultos\"<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-8212\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-8212\"><p><span class=\"s1\"><b>Estar en el mundo de los adultos, a trav\u00e9s de la imitaci\u00f3n, es la primera etapa de un viaje que lleva al ni\u00f1o a adquirir nuevas habilidades.<br \/>\n<\/b><\/span><span style=\"font-size: 20px;\">Gradualmente, imitar le permite a tu hijo reproducir lo que ve, desarrollar su capacidad de simbolizar y posicionarse en una condici\u00f3n social. <\/span><span style=\"font-size: 20px;\">\u00a1Gracias al realismo de nuestros veh\u00edculos y su gran jugabilidad, su hijo puede inventar una infinidad de historias en la que a veces ser\u00e1 jardinero, jefe de construcci\u00f3n o piloto de carreras!<\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1097a8d3 elementor-hidden-desktop elementor-hidden-tablet elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"1097a8d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">NUESTROS COMPROMISOS<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7aa6916d elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-toggle\" data-id=\"7aa6916d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2051\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2051\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Hecho en Francia desde ... siempre!<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2051\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2051\"><p><span class=\"s1\"><b> Desde el principio, Falk Toys asume el reto de imaginar, dise\u00f1ar y fabricar sus juguetes en Francia, en concreto, en nuestros talleres de Oyonnax (regi\u00f3n R\u00f3dano-Alpes trabajando con socios locales con el fin de dinamizar la actividad econ\u00f3mica de nuestra regi\u00f3n.<br \/>\n<\/b><\/span><span style=\"font-size: 20px;\">\u00a1A este respecto, Falk Toys exhibe ahora con orgullo el sello Origin\u2019Ain, plasmaci\u00f3n de un proceso iniciado hace m\u00e1s de 70 a\u00f3s!<\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2052\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2052\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">El aire libre, fundamental en nuestra profesi\u00f3n...<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2052\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2052\"><p><strong><span class=\"s1\">Rodeados de lagos, monta\u00f1as y bosques, hicimos del cielo abierto nuestro oficio principal. Crecer divirti\u00e9ndose, y cuando es posible a cierta distancia de la televisi\u00f3n, volver a conectarse con el placer de jugar en el exterior, llueva, ventee o nieve.<br \/>\n<\/span><\/strong><span class=\"s1\">Proveniente de una regi\u00f3n donde la naturaleza es omnipresente, el ADN de Falk lo es todo: hacer que los juguetes al aire libre sean lo suficientemente resistentes como para soportar a los ni\u00f1os m\u00e1s intr\u00e9pidos.<\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2053\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2053\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Pedales en lugar de una bater\u00eda, para el planeta y su salud.<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2053\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2053\"><p><strong><span class=\"s1\">Una elecci\u00f3n \u00e9tica, para su salud, porque creemos que la infancia est\u00e1 hecha para andar, correr, pedalear, saltar en los charcos, ensuciarse y construir recuerdos imperecederos siendo el actor de su propio juego.<br \/>\n<\/span><\/strong><span class=\"s1\">Una opci\u00f3n para el planeta tambi\u00e9n, porque la naturaleza es un magn\u00edfico patio de recreo, ya que la conservamos al limitar nuestro impacto ecol\u00f3gico. Por todas estas razones, elegimos no usar bater\u00edas para nuestros juguetes.<\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2054\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2054\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Un servicio postventa a tu servicio<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2054\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2054\"><p><strong><span class=\"s1\">Para brindarte una satisfacci\u00f3n total, nuestro servicio postventa est\u00e1 a tu disposici\u00f3n para responder r\u00e1pidamente a tus <span class=\"Apple-converted-space\">preguntas<\/span> en caso de un problema.<br \/>\n<\/span><\/strong><span class=\"s1\">Para cualquier queja, ve a nuestra \u00e1rea encargada : <strong><a href=\"https:\/\/falk-toys.com\/es\/servicio-postventa\/\">p\u00e1gina servicio postventa<\/a><\/strong><span class=\"Apple-converted-space\"> , <\/span>para completar nuestro formulario de soporte para su solicitud de servicio postventa. Nosotros nos encargamos del resto!<\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55f73298 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-phone elementor-widget elementor-widget-heading\" data-id=\"55f73298\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FIN SECTION MOBILE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-688551c elementor-hidden-phone elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"688551c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8fdc95c\" data-id=\"8fdc95c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a86752e elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"3a86752e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Los retos de las habilidades motoras<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a42c5b elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"1a42c5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\"><span class=\"s1\"><strong>Durante sus primeros 3 a\u00f1os, el ni\u00f1o desarrollar\u00e1 sus habilidades psicomotoras.<\/strong>\n<\/span><\/p><br>\n<p class=\"p1\"><span class=\"s1\">Caminar, correr, empujar, pedalear son actividades que le permitir\u00e1n a su hijo desarrollar sus habilidades motoras globales, un prerrequisito fundamental para el desarrollo de la psicomotricidad fina y m\u00e1s tarde para aprender en la escuela. \u00a1Falk acompa\u00f1a a su hijo en el desarrollo de sus nuevas habilidades mientras se divierte!<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6a918704\" data-id=\"6a918704\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-393f130d elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"393f130d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hacer como \u00ab&nbsp;los adultos&nbsp;\u00bb<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-349e5e2a elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"349e5e2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\"><strong><span class=\"s1\">Estar en el mundo de los adultos, a trav\u00e9s de la imitaci\u00f3n, es la primera etapa de un viaje que lleva al ni\u00f1o a adquirir nuevas habilidades.<\/span><\/strong><\/p><br>\n<p class=\"p1\"><span class=\"s1\">Gradualmente, imitar le permite a tu hijo reproducir lo que ve, desarrollar su capacidad de simbolizar y posicionarse en una condici\u00f3n social.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">\u00a1Gracias al realismo de nuestros veh\u00edculos y su gran jugabilidad, su hijo puede inventar una infinidad de historias en la que a veces ser\u00e1 jardinero, jefe de construcci\u00f3n o piloto de carreras!<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3bcbe749 elementor-hidden-phone elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3bcbe749\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5cce3be1\" data-id=\"5cce3be1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-53ee120b elementor-invisible elementor-widget elementor-widget-image\" data-id=\"53ee120b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1100\" height=\"652\" src=\"https:\/\/falk-toys.com\/wp-content\/uploads\/2025\/10\/996_01.jpg\" class=\"attachment-full size-full wp-image-31419\" alt=\"\" srcset=\"https:\/\/falk-toys.com\/wp-content\/uploads\/2025\/10\/996_01.jpg 1100w, https:\/\/falk-toys.com\/wp-content\/uploads\/2025\/10\/996_01-600x356.jpg 600w, https:\/\/falk-toys.com\/wp-content\/uploads\/2025\/10\/996_01-300x178.jpg 300w, https:\/\/falk-toys.com\/wp-content\/uploads\/2025\/10\/996_01-1024x607.jpg 1024w, https:\/\/falk-toys.com\/wp-content\/uploads\/2025\/10\/996_01-768x455.jpg 768w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1448994b elementor-hidden-phone elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1448994b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-38b8adb7\" data-id=\"38b8adb7\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-778cf87c elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"778cf87c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">NUESTROS COMPROMISOS<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-248e0b40 elementor-hidden-phone elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"248e0b40\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-11f78ac9\" data-id=\"11f78ac9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1207d63d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1207d63d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-668e1ea4\" data-id=\"668e1ea4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54e6a071 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"54e6a071\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hecho en Francia desde ... siempre!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78d422b1 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"78d422b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\"><strong><span class=\"s1\">Desde el principio, Falk Toys asume el reto de imaginar, dise\u00f1ar y fabricar sus juguetes en Francia, en concreto, en nuestros talleres de Oyonnax (regi\u00f3n R\u00f3dano-Alpes trabajando con socios locales con el fin de dinamizar la actividad econ\u00f3mica de nuestra regi\u00f3n.<\/span><\/strong><\/p><br>\n<p class=\"p1\"><span class=\"s1\">\u00a1A este respecto, Falk Toys exhibe ahora con orgullo el sello Origin\u2019Ain, plasmaci\u00f3n de un proceso iniciado hace m\u00e1s de 70 a\u00f3s!<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4102bbe2\" data-id=\"4102bbe2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-538139c4 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"538139c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">El aire libre, fundamental en nuestra profesi\u00f3n...<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24589da4 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"24589da4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Rodeados de lagos, monta\u00f1as y bosques, hicimos del cielo abierto nuestro oficio principal. Crecer divirti\u00e9ndose, y cuando es posible a cierta distancia de la televisi\u00f3n, volver a conectarse con el placer de jugar en el exterior, llueva, ventee o nieve.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Proveniente de una regi\u00f3n donde la naturaleza es omnipresente, el ADN de Falk lo es todo: hacer que los juguetes al aire libre sean lo suficientemente resistentes como para soportar a los ni\u00f1os m\u00e1s intr\u00e9pidos.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-708f51a6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"708f51a6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1466ef79\" data-id=\"1466ef79\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3799cced elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"3799cced\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:700}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pedales en lugar de una bater\u00eda, para el planeta y su salud.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-732b89f7 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"732b89f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:1200}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\"><strong><span class=\"s1\">Una elecci\u00f3n \u00e9tica, para su salud, porque creemos que la infancia est\u00e1 hecha para andar, correr, pedalear, saltar en los charcos, ensuciarse y construir recuerdos imperecederos siendo el actor de su propio juego.<\/span><\/strong><\/p><br>\n<p class=\"p1\"><span class=\"s1\">Una opci\u00f3n para el planeta tambi\u00e9n, porque la naturaleza es un magn\u00edfico patio de recreo, ya que la conservamos al limitar nuestro impacto ecol\u00f3gico. Por todas estas razones, elegimos no usar bater\u00edas para nuestros juguetes.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-73ebf9d2\" data-id=\"73ebf9d2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64be723c elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"64be723c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:700}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Un servicio postventa a tu servicio<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77839316 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"77839316\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:1200}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\"><strong><span class=\"s1\">Para brindarte una satisfacci\u00f3n total, nuestro servicio postventa est\u00e1 a tu disposici\u00f3n para responder r\u00e1pidamente a tus <span class=\"Apple-converted-space\">preguntas<\/span> en caso de un problema.<\/span><\/strong><\/p><br>\n<p class=\"p1\"><span class=\"s1\">\u00a1Para cualquier queja, ve a nuestra \u00c3\u00a1rea encargada : <span style=\"text-decoration: underline;\"><strong><span style=\"color: #ffffff; text-decoration: underline;\"><a style=\"color: #ffffff; text-decoration: underline;\" href=\"https:\/\/falk-toys.com\/es\/servicio-postventa\/\">p\u00e1gina servicio postventa SAV<\/a><\/span><\/strong><\/span><span class=\"Apple-converted-space\"> ,<\/span>para completar nuestro formulario de soporte para su solicitud de servicio postventa. Nosotros nos encargamos del resto! Nosotros nos encargamos del resto!<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-59518d33 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"59518d33\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6c7d794c\" data-id=\"6c7d794c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-477795c4 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"477795c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;rollIn&quot;,&quot;_animation_delay&quot;:1200}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"132\" height=\"75\" src=\"https:\/\/falk-toys.com\/wp-content\/uploads\/2019\/12\/falk-tounevis.png\" class=\"attachment-full size-full wp-image-633\" alt=\"tournevis blanc\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5dd9dcc5 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"5dd9dcc5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;],&quot;background_motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}}}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4377f8b4\" data-id=\"4377f8b4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2d5f8fe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2d5f8fe\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-38de6177\" data-id=\"38de6177\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ac2fd3c elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"3ac2fd3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">\u00a1Falk, una historia familiar<br>para 3 generaciones! <\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d4d2219 elementor-hidden-phone elementor-invisible elementor-widget elementor-widget-image\" data-id=\"2d4d2219\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"319\" height=\"172\" src=\"https:\/\/falk-toys.com\/wp-content\/uploads\/2019\/12\/yvain-sogno.png\" class=\"attachment-full size-full wp-image-1078\" alt=\"photos portraits des dirigeants de Falk\" srcset=\"https:\/\/falk-toys.com\/wp-content\/uploads\/2019\/12\/yvain-sogno.png 319w, https:\/\/falk-toys.com\/wp-content\/uploads\/2019\/12\/yvain-sogno-300x162.png 300w\" sizes=\"(max-width: 319px) 100vw, 319px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-997590f elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"997590f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:700}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Una historia familiar sobre la pasi\u00f3n del juguete<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6049d7fc elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"6049d7fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:700}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\"><span class=\"s1\">Los or\u00edgenes de Falk se remontan en Falquet, el apellido de Maurice Falquet, fundador de la marca Falk Toys en 1947. Su sobrino Didier Sogno se uni\u00f3 a \u00e9l en 1970 como director comercial y se hizo cargo en 2002 con la misi\u00f3n de desarrollar la presencia de Falk. al internacional. Hijo de Didier Sogno, Yvain integra la compa\u00f1\u00eda en 2007 para finalmente tomar la iniciativa en 2014. Modernizar\u00eda y racionalizar\u00eda la producci\u00f3n como tambi\u00e9n la gama de productos mediante el desarrollo de los tratados con los fabricantes de veh\u00edculos !<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-338ea28b elementor-hidden-phone elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"338ea28b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-406925c\" data-id=\"406925c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-49664707 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"49664707\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-407bb5cb\" data-id=\"407bb5cb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-675b16a5 pp-info-box-top elementor-invisible elementor-widget elementor-widget-pp-info-box\" data-id=\"675b16a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomInUp&quot;}\" data-widget_type=\"pp-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"pp-info-box-container\">\n\t\t\t<div class=\"pp-info-box\">\n\t\t\t\t\t\t\t\t\t<div class=\"pp-info-box-icon-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-info-box-icon pp-icon\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"260\" height=\"260\" src=\"https:\/\/falk-toys.com\/wp-content\/uploads\/2019\/12\/vignettes-historique-1947.png\" class=\"attachment-full size-full wp-image-1083\" alt=\"bateau en plastique\" srcset=\"https:\/\/falk-toys.com\/wp-content\/uploads\/2019\/12\/vignettes-historique-1947.png 260w, https:\/\/falk-toys.com\/wp-content\/uploads\/2019\/12\/vignettes-historique-1947-100x100.png 100w, https:\/\/falk-toys.com\/wp-content\/uploads\/2019\/12\/vignettes-historique-1947-150x150.png 150w\" sizes=\"(max-width: 260px) 100vw, 260px\" \/>\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"pp-info-box-content\">\n\t\t\t\t\t<div class=\"pp-info-box-title-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-info-box-title-container\">\n\t\t\t\t\t\t\t\t<h4 class=\"pp-info-box-title\">\n\t\t\t\t\t\t\t\t\t1947\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h5 class=\"pp-info-box-subtitle\">\n\t\t\t\t\t\t\t\t\u00c9rase una vez\t\t\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-info-box-description\">\n\t\t\t\t\t\t\tLa historia de los juguetes Falk comienza en 1947, bajo la direcci\u00f3n de Maurice Falquet. En ese momento, la empresa est\u00e1 especializada en la fabricaci\u00f3n y comercializaci\u00f3n de varios juguetes de pl\u00e1stico.\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4b6973c3\" data-id=\"4b6973c3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56c996f6 pp-info-box-top elementor-invisible elementor-widget elementor-widget-pp-info-box\" data-id=\"56c996f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomInUp&quot;}\" data-widget_type=\"pp-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"pp-info-box-container\">\n\t\t\t<div class=\"pp-info-box\">\n\t\t\t\t\t\t\t\t\t<div class=\"pp-info-box-icon-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-info-box-icon pp-icon\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"260\" height=\"260\" src=\"https:\/\/falk-toys.com\/wp-content\/uploads\/2019\/12\/vignettes-historique-1970.png\" class=\"attachment-full size-full wp-image-1087\" alt=\"vielle photo d&#039;un enfant avec un tracteur Falk Toys\" srcset=\"https:\/\/falk-toys.com\/wp-content\/uploads\/2019\/12\/vignettes-historique-1970.png 260w, https:\/\/falk-toys.com\/wp-content\/uploads\/2019\/12\/vignettes-historique-1970-100x100.png 100w, https:\/\/falk-toys.com\/wp-content\/uploads\/2019\/12\/vignettes-historique-1970-150x150.png 150w\" sizes=\"(max-width: 260px) 100vw, 260px\" \/>\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"pp-info-box-content\">\n\t\t\t\t\t<div class=\"pp-info-box-title-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-info-box-title-container\">\n\t\t\t\t\t\t\t\t<h4 class=\"pp-info-box-title\">\n\t\t\t\t\t\t\t\t\t1970\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h5 class=\"pp-info-box-subtitle\">\n\t\t\t\t\t\t\t\t\u00a1Siempre adelante!\t\t\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-info-box-description\">\n\t\t\t\t\t\t\tFalk lanza su primer tractor de pedales. Luego escribieron las primeras p\u00e1ginas de un largo camino de \u00e9xito 100% hecho en Francia.\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-f79e1e9\" data-id=\"f79e1e9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6304066d pp-info-box-top elementor-invisible elementor-widget elementor-widget-pp-info-box\" data-id=\"6304066d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomInUp&quot;}\" data-widget_type=\"pp-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"pp-info-box-container\">\n\t\t\t<div class=\"pp-info-box\">\n\t\t\t\t\t\t\t\t\t<div class=\"pp-info-box-icon-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-info-box-icon pp-icon\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"260\" height=\"260\" src=\"https:\/\/falk-toys.com\/wp-content\/uploads\/2019\/12\/1977-falk-toys-min.png\" class=\"attachment-full size-full wp-image-1091\" alt=\"\" srcset=\"https:\/\/falk-toys.com\/wp-content\/uploads\/2019\/12\/1977-falk-toys-min.png 260w, https:\/\/falk-toys.com\/wp-content\/uploads\/2019\/12\/1977-falk-toys-min-100x100.png 100w, https:\/\/falk-toys.com\/wp-content\/uploads\/2019\/12\/1977-falk-toys-min-150x150.png 150w\" sizes=\"(max-width: 260px) 100vw, 260px\" \/>\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"pp-info-box-content\">\n\t\t\t\t\t<div class=\"pp-info-box-title-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-info-box-title-container\">\n\t\t\t\t\t\t\t\t<h4 class=\"pp-info-box-title\">\n\t\t\t\t\t\t\t\t\t1977\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h5 class=\"pp-info-box-subtitle\">\n\t\t\t\t\t\t\t\t\u00a1Como los de verdad !\t\t\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-info-box-description\">\n\t\t\t\t\t\t\tDidier Sogno, sobrino de Maurice Falquet, se une a Falk Toys como Director Comercial y desarrolla la oferta con la licencia de Ford, Massey Ferguson y Renault con un modelo ic\u00f3nico: \u00a1El Turbo TX , que vendi\u00f3 m\u00e1s de 750,000 copias!\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7ec2e6ea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7ec2e6ea\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-799634a2\" data-id=\"799634a2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e86bdf6 pp-info-box-top elementor-invisible elementor-widget elementor-widget-pp-info-box\" data-id=\"6e86bdf6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomInUp&quot;}\" data-widget_type=\"pp-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"pp-info-box-container\">\n\t\t\t<div class=\"pp-info-box\">\n\t\t\t\t\t\t\t\t\t<div class=\"pp-info-box-icon-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-info-box-icon pp-icon\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"260\" height=\"260\" src=\"https:\/\/falk-toys.com\/wp-content\/uploads\/2019\/12\/2002-falk-toys-min.png\" class=\"attachment-full size-full wp-image-1095\" alt=\"usine de fabrication Falk Toys\" srcset=\"https:\/\/falk-toys.com\/wp-content\/uploads\/2019\/12\/2002-falk-toys-min.png 260w, https:\/\/falk-toys.com\/wp-content\/uploads\/2019\/12\/2002-falk-toys-min-100x100.png 100w, https:\/\/falk-toys.com\/wp-content\/uploads\/2019\/12\/2002-falk-toys-min-150x150.png 150w\" sizes=\"(max-width: 260px) 100vw, 260px\" \/>\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"pp-info-box-content\">\n\t\t\t\t\t<div class=\"pp-info-box-title-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-info-box-title-container\">\n\t\t\t\t\t\t\t\t<h4 class=\"pp-info-box-title\">\n\t\t\t\t\t\t\t\t\t2002\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h5 class=\"pp-info-box-subtitle\">\n\t\t\t\t\t\t\t\tHELLO WORLD\t\t\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-info-box-description\">\n\t\t\t\t\t\t\tDidier Sogno se convierte en el presidente de Falk Toys y expande enormemente el mercado de exportaci\u00f3n. \u00a1Hoy encontramos juguetes Falk en m\u00e1s de 40 pa\u00edses!\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1eeb5724\" data-id=\"1eeb5724\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f35e39f pp-info-box-top elementor-invisible elementor-widget elementor-widget-pp-info-box\" data-id=\"7f35e39f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomInUp&quot;}\" data-widget_type=\"pp-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"pp-info-box-container\">\n\t\t\t<div class=\"pp-info-box\">\n\t\t\t\t\t\t\t\t\t<div class=\"pp-info-box-icon-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-info-box-icon pp-icon\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"260\" height=\"260\" src=\"https:\/\/falk-toys.com\/wp-content\/uploads\/2019\/12\/2007-falk-toys-min.png\" class=\"attachment-full size-full wp-image-1099\" alt=\"jouet roulant\" srcset=\"https:\/\/falk-toys.com\/wp-content\/uploads\/2019\/12\/2007-falk-toys-min.png 260w, https:\/\/falk-toys.com\/wp-content\/uploads\/2019\/12\/2007-falk-toys-min-100x100.png 100w, https:\/\/falk-toys.com\/wp-content\/uploads\/2019\/12\/2007-falk-toys-min-150x150.png 150w\" sizes=\"(max-width: 260px) 100vw, 260px\" \/>\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"pp-info-box-content\">\n\t\t\t\t\t<div class=\"pp-info-box-title-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-info-box-title-container\">\n\t\t\t\t\t\t\t\t<h4 class=\"pp-info-box-title\">\n\t\t\t\t\t\t\t\t\t2007\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h5 class=\"pp-info-box-subtitle\">\n\t\t\t\t\t\t\t\tMaquinas geniales\t\t\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-info-box-description\">\n\t\t\t\t\t\t\tYvain Sogno, hijo de Didier Sogno, se une a la compa\u00f1\u00eda Falk como Gerente General. Su llegada marca el lanzamiento de una importante campa\u00f1a para modernizar la producci\u00f3n. \u00a1Falk Toys est\u00e1 m\u00e1s que nunca mirando hacia el futuro!\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6c02786f\" data-id=\"6c02786f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71bfe89b pp-info-box-top elementor-invisible elementor-widget elementor-widget-pp-info-box\" data-id=\"71bfe89b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomInUp&quot;}\" data-widget_type=\"pp-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"pp-info-box-container\">\n\t\t\t<div class=\"pp-info-box\">\n\t\t\t\t\t\t\t\t\t<div class=\"pp-info-box-icon-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-info-box-icon pp-icon\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"260\" height=\"260\" src=\"https:\/\/falk-toys.com\/wp-content\/uploads\/2019\/12\/2014-falk-on-the-road.png\" class=\"attachment-full size-full wp-image-1103\" alt=\"enfant sur un jouet roulant rouge\" srcset=\"https:\/\/falk-toys.com\/wp-content\/uploads\/2019\/12\/2014-falk-on-the-road.png 260w, https:\/\/falk-toys.com\/wp-content\/uploads\/2019\/12\/2014-falk-on-the-road-100x100.png 100w, https:\/\/falk-toys.com\/wp-content\/uploads\/2019\/12\/2014-falk-on-the-road-150x150.png 150w\" sizes=\"(max-width: 260px) 100vw, 260px\" \/>\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"pp-info-box-content\">\n\t\t\t\t\t<div class=\"pp-info-box-title-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-info-box-title-container\">\n\t\t\t\t\t\t\t\t<h4 class=\"pp-info-box-title\">\n\t\t\t\t\t\t\t\t\t2014\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h5 class=\"pp-info-box-subtitle\">\n\t\t\t\t\t\t\t\tFALK on the road\t\t\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-info-box-description\">\n\t\t\t\t\t\t\tYvain Sogno es el nuevo Gerente General de Falk Toys desde 2014. \u00a1Desde entonces, la marca francesa renueva constantemente su experiencia en juguetes sobre ruedas para servir a nuevos tipos de veh\u00edculos, con el objetivo de hacer de los productos Falk un juguete imprescindible!\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-69ec761d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"69ec761d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-713127b5\" data-id=\"713127b5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2764ef87\" data-id=\"2764ef87\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e48c09e elementor-invisible elementor-widget elementor-widget-image\" data-id=\"7e48c09e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"399\" height=\"200\" src=\"https:\/\/falk-toys.com\/wp-content\/uploads\/2019\/12\/collines.png\" class=\"attachment-full size-full wp-image-356\" alt=\"colline d&#039;Oyonnax\" srcset=\"https:\/\/falk-toys.com\/wp-content\/uploads\/2019\/12\/collines.png 399w, https:\/\/falk-toys.com\/wp-content\/uploads\/2019\/12\/collines-300x150.png 300w\" sizes=\"(max-width: 399px) 100vw, 399px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>CRECER CON FALK TOYS DEBUT SECTION MOBILE CRECER CON FALK TOYS Los retos de las habilidades motoras Durante sus primeros 3 a\u00f1os, el ni\u00f1o desarrollar\u00e1 sus habilidades psicomotoras. Caminar, correr, empujar, pedalear son actividades que le permitir\u00e1n a su hijo desarrollar sus habilidades motoras globales, un prerrequisito fundamental para el desarrollo de la psicomotricidad fina [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-1413","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.8 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Crecer bien con Falk Toys | FALK - Toys that rolls<\/title>\n<meta name=\"description\" content=\"\u00a1Los ni\u00f1os est\u00e1n llenos de energ\u00eda! \u00a1Para crecer bien, se tienen que gastar! Hacemos juguetes sobre ruedas para pedalear y descubrir el mundo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/falk-toys.com\/es\/crecer-con-falk-toys\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Crecer con Falk Toys\" \/>\n<meta property=\"og:description\" content=\"\u00a1Los ni\u00f1os est\u00e1n llenos de energ\u00eda! \u00a1Para crecer bien, se tienen que gastar! Hacemos juguetes sobre ruedas para pedalear y descubrir el mundo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/falk-toys.com\/es\/crecer-con-falk-toys\/\" \/>\n<meta property=\"og:site_name\" content=\"FALK - Toys that rolls\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FalkFR\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-21T07:54:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/falk-toys.com\/wp-content\/uploads\/2025\/10\/996_01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"652\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/falk-toys.com\\\/es\\\/crecer-con-falk-toys\\\/\",\"url\":\"https:\\\/\\\/falk-toys.com\\\/es\\\/crecer-con-falk-toys\\\/\",\"name\":\"Crecer bien con Falk Toys | FALK - Toys that rolls\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/falk-toys.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/falk-toys.com\\\/es\\\/crecer-con-falk-toys\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/falk-toys.com\\\/es\\\/crecer-con-falk-toys\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/falk-toys.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/996_01.jpg\",\"datePublished\":\"2019-12-13T20:15:36+00:00\",\"dateModified\":\"2025-10-21T07:54:42+00:00\",\"description\":\"\u00a1Los ni\u00f1os est\u00e1n llenos de energ\u00eda! \u00a1Para crecer bien, se tienen que gastar! Hacemos juguetes sobre ruedas para pedalear y descubrir el mundo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/falk-toys.com\\\/es\\\/crecer-con-falk-toys\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/falk-toys.com\\\/es\\\/crecer-con-falk-toys\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/falk-toys.com\\\/es\\\/crecer-con-falk-toys\\\/#primaryimage\",\"url\":\"https:\\\/\\\/falk-toys.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/996_01.jpg\",\"contentUrl\":\"https:\\\/\\\/falk-toys.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/996_01.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/falk-toys.com\\\/es\\\/crecer-con-falk-toys\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/falk-toys.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Crecer con Falk Toys\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/falk-toys.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/falk-toys.com\\\/es\\\/\",\"name\":\"FALK - Toys that rolls\",\"description\":\"Jouets fabriqu\u00e9s en France\",\"publisher\":{\"@id\":\"https:\\\/\\\/falk-toys.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/falk-toys.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/falk-toys.com\\\/es\\\/#organization\",\"name\":\"Falk Toys\",\"url\":\"https:\\\/\\\/falk-toys.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/falk-toys.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/falk-toys.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/falk-logo@2x.png\",\"contentUrl\":\"https:\\\/\\\/falk-toys.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/falk-logo@2x.png\",\"width\":436,\"height\":351,\"caption\":\"Falk Toys\"},\"image\":{\"@id\":\"https:\\\/\\\/falk-toys.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FalkFR\\\/\",\"https:\\\/\\\/www.instagram.com\\\/falk_toys\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCKZXf1_E8UsPhjAQo-Y5vlg\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Crecer bien con Falk Toys | FALK - Toys that rolls","description":"\u00a1Los ni\u00f1os est\u00e1n llenos de energ\u00eda! \u00a1Para crecer bien, se tienen que gastar! Hacemos juguetes sobre ruedas para pedalear y descubrir el mundo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/falk-toys.com\/es\/crecer-con-falk-toys\/","og_locale":"es_ES","og_type":"article","og_title":"Crecer con Falk Toys","og_description":"\u00a1Los ni\u00f1os est\u00e1n llenos de energ\u00eda! \u00a1Para crecer bien, se tienen que gastar! Hacemos juguetes sobre ruedas para pedalear y descubrir el mundo.","og_url":"https:\/\/falk-toys.com\/es\/crecer-con-falk-toys\/","og_site_name":"FALK - Toys that rolls","article_publisher":"https:\/\/www.facebook.com\/FalkFR\/","article_modified_time":"2025-10-21T07:54:42+00:00","og_image":[{"width":1100,"height":652,"url":"https:\/\/falk-toys.com\/wp-content\/uploads\/2025\/10\/996_01.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/falk-toys.com\/es\/crecer-con-falk-toys\/","url":"https:\/\/falk-toys.com\/es\/crecer-con-falk-toys\/","name":"Crecer bien con Falk Toys | FALK - Toys that rolls","isPartOf":{"@id":"https:\/\/falk-toys.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/falk-toys.com\/es\/crecer-con-falk-toys\/#primaryimage"},"image":{"@id":"https:\/\/falk-toys.com\/es\/crecer-con-falk-toys\/#primaryimage"},"thumbnailUrl":"https:\/\/falk-toys.com\/wp-content\/uploads\/2025\/10\/996_01.jpg","datePublished":"2019-12-13T20:15:36+00:00","dateModified":"2025-10-21T07:54:42+00:00","description":"\u00a1Los ni\u00f1os est\u00e1n llenos de energ\u00eda! \u00a1Para crecer bien, se tienen que gastar! Hacemos juguetes sobre ruedas para pedalear y descubrir el mundo.","breadcrumb":{"@id":"https:\/\/falk-toys.com\/es\/crecer-con-falk-toys\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/falk-toys.com\/es\/crecer-con-falk-toys\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/falk-toys.com\/es\/crecer-con-falk-toys\/#primaryimage","url":"https:\/\/falk-toys.com\/wp-content\/uploads\/2025\/10\/996_01.jpg","contentUrl":"https:\/\/falk-toys.com\/wp-content\/uploads\/2025\/10\/996_01.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/falk-toys.com\/es\/crecer-con-falk-toys\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/falk-toys.com\/es\/"},{"@type":"ListItem","position":2,"name":"Crecer con Falk Toys"}]},{"@type":"WebSite","@id":"https:\/\/falk-toys.com\/es\/#website","url":"https:\/\/falk-toys.com\/es\/","name":"FALK - Toys that rolls","description":"Jouets fabriqu\u00e9s en France","publisher":{"@id":"https:\/\/falk-toys.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/falk-toys.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/falk-toys.com\/es\/#organization","name":"Falk Toys","url":"https:\/\/falk-toys.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/falk-toys.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/falk-toys.com\/wp-content\/uploads\/2019\/12\/falk-logo@2x.png","contentUrl":"https:\/\/falk-toys.com\/wp-content\/uploads\/2019\/12\/falk-logo@2x.png","width":436,"height":351,"caption":"Falk Toys"},"image":{"@id":"https:\/\/falk-toys.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FalkFR\/","https:\/\/www.instagram.com\/falk_toys\/","https:\/\/www.youtube.com\/channel\/UCKZXf1_E8UsPhjAQo-Y5vlg"]}]}},"_links":{"self":[{"href":"https:\/\/falk-toys.com\/es\/wp-json\/wp\/v2\/pages\/1413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/falk-toys.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/falk-toys.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/falk-toys.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/falk-toys.com\/es\/wp-json\/wp\/v2\/comments?post=1413"}],"version-history":[{"count":0,"href":"https:\/\/falk-toys.com\/es\/wp-json\/wp\/v2\/pages\/1413\/revisions"}],"wp:attachment":[{"href":"https:\/\/falk-toys.com\/es\/wp-json\/wp\/v2\/media?parent=1413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}